{"id":622,"count":1,"description":"","link":"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/","name":"CUT OFF DISCS","slug":"cut-off-discs","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CUT OFF DISCS Archives - Allied Bolt<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CUT OFF DISCS Archives - Allied Bolt\" \/>\n<meta property=\"og:url\" content=\"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/\" \/>\n<meta property=\"og:site_name\" content=\"Allied Bolt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/site.alliedbolt.com\\\/blog\\\/tag\\\/cut-off-discs\\\/\",\"url\":\"https:\\\/\\\/site.alliedbolt.com\\\/blog\\\/tag\\\/cut-off-discs\\\/\",\"name\":\"CUT OFF DISCS Archives - Allied Bolt\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/site.alliedbolt.com\\\/blog\\\/tag\\\/cut-off-discs\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/site.alliedbolt.com\\\/blog\\\/tag\\\/cut-off-discs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CUT OFF DISCS\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/\",\"name\":\"Allied Bolt\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/#organization\",\"name\":\"Allied Bolt\",\"url\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/site.alliedbolt.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-allied-logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/site.alliedbolt.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-allied-logo-1.jpg\",\"width\":453,\"height\":160,\"caption\":\"Allied Bolt\"},\"image\":{\"@id\":\"http:\\\/\\\/site.alliedbolt.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/alliedbolt\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/neil-goldberg-25329a43\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CUT OFF DISCS Archives - Allied Bolt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/","og_locale":"en_US","og_type":"article","og_title":"CUT OFF DISCS Archives - Allied Bolt","og_url":"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/","og_site_name":"Allied Bolt","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/","url":"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/","name":"CUT OFF DISCS Archives - Allied Bolt","isPartOf":{"@id":"http:\/\/site.alliedbolt.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/site.alliedbolt.com\/blog\/tag\/cut-off-discs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/site.alliedbolt.com\/blog\/"},{"@type":"ListItem","position":2,"name":"CUT OFF DISCS"}]},{"@type":"WebSite","@id":"http:\/\/site.alliedbolt.com\/blog\/#website","url":"http:\/\/site.alliedbolt.com\/blog\/","name":"Allied Bolt","description":"","publisher":{"@id":"http:\/\/site.alliedbolt.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/site.alliedbolt.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/site.alliedbolt.com\/blog\/#organization","name":"Allied Bolt","url":"http:\/\/site.alliedbolt.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/site.alliedbolt.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/site.alliedbolt.com\/blog\/wp-content\/uploads\/2023\/05\/cropped-allied-logo-1.jpg","contentUrl":"https:\/\/site.alliedbolt.com\/blog\/wp-content\/uploads\/2023\/05\/cropped-allied-logo-1.jpg","width":453,"height":160,"caption":"Allied Bolt"},"image":{"@id":"http:\/\/site.alliedbolt.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/alliedbolt","https:\/\/www.linkedin.com\/in\/neil-goldberg-25329a43\/"]}]}},"_links":{"self":[{"href":"https:\/\/site.alliedbolt.com\/blog\/wp-json\/wp\/v2\/tags\/622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site.alliedbolt.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/site.alliedbolt.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/site.alliedbolt.com\/blog\/wp-json\/wp\/v2\/posts?tags=622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}